{"id":19737,"date":"2021-03-08T20:17:52","date_gmt":"2021-03-08T20:17:52","guid":{"rendered":"https:\/\/gflenv.com\/gfl-environmental-and-waste-industries-annonce-une-fusion-creant-une-entreprise-de-services-environnementaux-de-premier-plan-en-amerique-du-nord\/"},"modified":"2022-10-10T20:21:25","modified_gmt":"2022-10-10T20:21:25","slug":"gfl-environmental-and-waste-industries-annonce-une-fusion-creant-une-entreprise-de-services-environnementaux-de-premier-plan-en-amerique-du-nord","status":"publish","type":"post","link":"https:\/\/gflenv.com\/fr\/gfl-environmental-and-waste-industries-annonce-une-fusion-creant-une-entreprise-de-services-environnementaux-de-premier-plan-en-amerique-du-nord\/","title":{"rendered":"GFL Environmental and Waste Industries annonce une fusion"},"content":{"rendered":"\n<p>TORONTO et RALEIGH, NC, 10 octobre 2018 \u2013 GFL Environmental Inc. (\u00ab GFL \u00bb) et Waste Industries ont annonc\u00e9 aujourd&#8217;hui qu&#8217;ils ont conclu une entente de fusion d\u00e9finitive dans le cadre d&#8217;une transaction qui \u00e9value Waste Industries \u00e0 une valeur totale d&#8217;entreprise de 2,825 milliards de dollars am\u00e9ricains (environ 3,65 milliards de dollars canadiens). La transaction, qui devrait \u00eatre conclue au quatri\u00e8me trimestre de 2018, est assujettie aux approbations r\u00e9glementaires habituelles.<\/p>\n\n\n\n<p>Apr\u00e8s sa recapitalisation termin\u00e9e en mai 2018 avec un consortium dirig\u00e9 par des soci\u00e9t\u00e9s affili\u00e9es de BC Partners (\u00ab BC Partners \u00bb) et incluant des soci\u00e9t\u00e9s affili\u00e9es du R\u00e9gime de retraite des enseignantes et des enseignants de l\u2019Ontario (\u00ab Ontario Teachers \u00bb) et d\u2019autres soci\u00e9t\u00e9s, GFL est l\u2019une des plus grandes soci\u00e9t\u00e9s de services environnementaux en Am\u00e9rique du Nord. Depuis sa fondation par la famille Poole en 1970, Waste Industries est devenue la premi\u00e8re soci\u00e9t\u00e9 ind\u00e9pendante de gestion des d\u00e9chets solides int\u00e9gr\u00e9e verticalement dans le sud-est des \u00c9tats-Unis. Lorsqu\u2019ils seront combin\u00e9s aux op\u00e9rations existantes de GFL en mati\u00e8re de d\u00e9chets solides, GFL et Waste Industries deviendront la plus grande entreprise priv\u00e9e de services environnementaux en Am\u00e9rique du Nord, avec des op\u00e9rations dans toutes les provinces canadiennes, \u00e0 l\u2019exception de l\u2019\u00cele-du-Prince-\u00c9douard et dans 10 \u00c9tats aux \u00c9tats-Unis. La soci\u00e9t\u00e9 fusionn\u00e9e exploitera 98 op\u00e9rations de collecte, 59 stations de transfert, 29 installations de r\u00e9cup\u00e9ration de mat\u00e9riel, 10 installations de mati\u00e8res organiques et 47 sites d\u2019enfouissement, et comptera plus de 8 850 employ\u00e9s. Patrick Dovigi continuera d\u2019\u00eatre le pr\u00e9sident et chef de la direction de l\u2019entreprise fusionn\u00e9e.<\/p>\n\n\n\n<p>\u00ab Waste Industries va plus que doubler l\u2019empreinte actuelle des op\u00e9rations de GFL aux \u00c9tats-Unis, ajout d\u2019une collection, station de transfert, les op\u00e9rations de r\u00e9cup\u00e9ration de mat\u00e9riaux et d\u2019enfouissement dans les march\u00e9s am\u00e9ricains en pleine croissance (y compris la Caroline du Nord, Caroline du Sud, G\u00e9orgie, Colorado, Tennessee, la Virginie et autres), la croissance de notre client\u00e8le et la cr\u00e9ation d\u2019une plateforme \u00e9tendue \u00e0 partir de laquelle GFL peut continuer \u00e0 mettre en \u0153uvre notre strat\u00e9gie de croissance biologique et d\u2019acquisition \u00e9prouv\u00e9e \u00bb, a dit Patrick Dovigi, le fondateur et pr\u00e9sident-directeur g\u00e9n\u00e9ral de GFL. \u00ab Waste Industries compl\u00e8te fortement la marque de GFL avec plus de 47 ans d\u2019exp\u00e9rience en mati\u00e8re de prestation d\u2019un excellent service \u00e0 la client\u00e8le \u00e0 ses communaut\u00e9s locales et dispose d\u2019une \u00e9quipe de gestion ayant fait ses preuves en mati\u00e8re de technologie, de processus et de syst\u00e8mes d\u2019exploitation pour favoriser l\u2019efficacit\u00e9 op\u00e9rationnelle. Nous sommes ravis d\u2019accueillir l\u2019\u00e9quipe de direction et plus de 2 850 employ\u00e9s de Waste Industries dans la famille GFL. \u00bb<\/p>\n\n\n\n<p>Ven Poole, pr\u00e9sident-directeur g\u00e9n\u00e9ral de Waste Industries, a d\u00e9clar\u00e9 : \u00ab L\u2019\u00e9volution continue de Waste Industries fait un autre grand pas en avant dans cette combinaison avec GFL. Ces entreprises se compl\u00e8tent mutuellement de plusieurs fa\u00e7ons et les \u00e9quipes de direction partagent une culture similaire ax\u00e9e sur un service \u00e0 la client\u00e8le exceptionnel, l\u2019excellence op\u00e9rationnelle et notre engagement \u00e0 faire une diff\u00e9rence dans les communaut\u00e9s que nous servons. La combinaison avec GFL offre un avenir tr\u00e8s brillant \u00e0 notre \u00e9quipe, et la famille Poole est fi\u00e8re de continuer \u00e0 investir gr\u00e2ce \u00e0 cette combinaison avec le v\u00e9ritable chef de file de l\u2019industrie en Am\u00e9rique du Nord, GFL. Je tiens \u00e0 remercier personnellement nos investisseurs, HPS et EGI pour la foi et le soutien qu\u2019ils ont montr\u00e9s \u00e0 l\u2019\u00e9quipe Waste Industries au cours de la derni\u00e8re ann\u00e9e, et je tiens \u00e0 assurer \u00e0 nos clients et communaut\u00e9s que les industries Waste Industries auxquelles vous faites confiance seront l\u00e0 pour vous servir pour les ann\u00e9es \u00e0 venir. \u00bb<\/p>\n\n\n\n<p>Certains actionnaires, y compris la famille de M. Poole fondateurs et les membres de la direction contribuent au capital engag\u00e9 et devraient devenir actionnaires de GFL dans le cadre de la transaction. Ven Poole, pr\u00e9sident-directeur g\u00e9n\u00e9ral actuel de Waste Industries, se joindra \u00e9galement au conseil d\u2019administration de GFL \u00e0 la conclusion de la transaction.<\/p>\n\n\n\n<p>Scot French, partenaire chez HPS Investment Partners, qui a dirig\u00e9 le groupe d&#8217;actionnaires actuel de Waste Industries, a d\u00e9clar\u00e9 : \u00ab Je tiens \u00e0 remercier toute l&#8217;\u00e9quipe de Waste Industries d&#8217;\u00eatre de bons partenaires. Nous avons une longue histoire avec GFL et nous avons pleinement confiance en l\u2019opportunit\u00e9 pour les deux entreprises ensemble qui nous attend. Nous sommes ravis de continuer \u00e0 investir dans le soutien de cette histoire de croissance remarquable. \u00bb<\/p>\n\n\n\n<p><strong>Financement des transactions<\/strong><\/p>\n\n\n\n<p>BC Partners, Ontario Teachers\u2019 et certains des autres actionnaires de GFL, y compris M. Dovigi, offrent un nouveau financement par actions pour la transaction. De plus, Barclays, la Banque de Montr\u00e9al, BMO March\u00e9s des capitaux et la Banque Royale du Canada offrent un financement par emprunt engag\u00e9. GFL s\u2019attend \u00e0 ce que le financement par emprunt consiste en une dette garantie et non garantie, qui sera utilis\u00e9e pour financer une partie du prix d\u2019achat et rembourser la dette existante de Waste Industries.<\/p>\n\n\n\n<p>Paolo Notarnicola, partenaire principal de GFL chez BC Partners, a ajout\u00e9 : \u00ab La fusion avec Waste Industries est une \u00e9tape importante dans notre th\u00e8se d\u2019investissement pour GFL : fournir le capital ainsi que le soutien strat\u00e9gique et op\u00e9rationnel pour acc\u00e9l\u00e9rer davantage la croissance d\u2019un champion canadien, en \u00e9troite collaboration avec Patrick et toute l\u2019\u00e9quipe de GFL. Nous sommes ravis de travailler avec Ven, Greg et l\u2019\u00e9quipe de Waste Industries pour atteindre notre objectif commun de construire la plateforme de consolidation pr\u00e9\u00e9minente pour les services environnementaux en Am\u00e9rique du Nord. \u00bb<\/p>\n\n\n\n<p>Simpson Thacher &amp; Bartlett LLP et Stikeman Elliott LLP ont agi \u00e0 titre de conseillers juridiques pour GFL. Latham &amp; Watkins LLP et Wyrick Robbins Yates &amp; Ponton LLP ont agi \u00e0 titre de conseillers juridiques de Waste Industries. Lee Lloyd a conseill\u00e9 la famille Poole.<\/p>\n\n\n\n<p><strong>Changements de dirigeant<\/strong><\/p>\n\n\n\n<p>En pr\u00e9vision de la cl\u00f4ture, GFL a \u00e9galement annonc\u00e9 aujourd\u2019hui que Luke Pelosi a \u00e9t\u00e9 nomm\u00e9 directeur financier pour remplacer David Bacon. \u00c0 la conclusion de la fusion, Greg Yorston occupera le poste de directeur de l\u2019exploitation pour toutes les op\u00e9rations de GFL au Canada et aux \u00c9tats-Unis. De plus, Ven Poole, pr\u00e9sident et chef de la direction actuel de Waste industries, agira \u00e0 titre de vice-pr\u00e9sident principal de la soci\u00e9t\u00e9 fusionn\u00e9e \u00e0 la suite de la transaction.<\/p>\n\n\n\n<p>M. Pelosi s\u2019est joint \u00e0 GFL en janvier 2015 \u00e0 titre de vice-pr\u00e9sident ex\u00e9cutif, D\u00e9veloppement de l\u2019entreprise. Il a ajout\u00e9 le r\u00f4le de directeur financier par int\u00e9rim de GFL de f\u00e9vrier \u00e0 mai 2017 et, depuis janvier 2018, il occupe le poste de directeur de l\u2019exploitation de GFL. M. Yorston poss\u00e8de plus de 30 ans d\u2019exp\u00e9rience dans l\u2019industrie des d\u00e9chets solides et a jou\u00e9 un r\u00f4le d\u00e9terminant dans la poursuite de l\u2019efficacit\u00e9 op\u00e9rationnelle depuis qu\u2019il a assum\u00e9 le r\u00f4le de directeur de l\u2019exploitation de Waste Industries en 2013.<\/p>\n\n\n\n<p><strong>\u00c0 propos de GFL<\/strong><\/p>\n\n\n\n<p>GFL, dont le si\u00e8ge social est situ\u00e9 \u00e0 Toronto, en Ontario, est une entreprise de services environnementaux diversifi\u00e9e qui offre une gamme compl\u00e8te de services de gestion des d\u00e9chets solides, d\u2019infrastructures et d\u2019assainissement du sol et de gestion des d\u00e9chets liquides par l\u2019interm\u00e9diaire de sa plateforme d\u2019installations au Canada et au Michigan. GFL compte plus de 6 000 employ\u00e9s et offre sa vaste gamme de services environnementaux \u00e0 plus de 60 000 clients commerciaux et industriels et ses services de collecte de d\u00e9chets solides \u00e0 plus de 2,3 millions de m\u00e9nages.<\/p>\n\n\n\n<p><strong>\u00c0 propos des industries des d\u00e9chets<\/strong><\/p>\n\n\n\n<p>Waste Industries est un fournisseur r\u00e9gional int\u00e9gr\u00e9 verticalement de services de collecte, de transfert, de recyclage et d\u2019\u00e9limination des d\u00e9chets solides non dangereux. Fond\u00e9e en 1970, la soci\u00e9t\u00e9 exerce actuellement ses activit\u00e9s en Caroline du Nord, en Caroline du Sud, en G\u00e9orgie, au Colorado, au Tennessee, en Virginie, au Maryland, en Pennsylvanie et au Delaware. Elle emploie plus de 2 850 personnes, dessert plus de 77 000 clients commerciaux et industriels et fournit des services de collecte de d\u00e9chets solides r\u00e9sidentiels \u00e0 environ 1,6 million de foyers.<\/p>\n\n\n\n<p><strong>\u00c0 propos des partenaires de la Colombie-<\/strong><\/p>\n\n\n\n<p>BC Partners est une soci\u00e9t\u00e9 d\u2019investissement internationale de premier plan avec plus de 20 milliards d\u2019euros d\u2019actifs sous gestion dans les domaines du capital-investissement et du cr\u00e9dit priv\u00e9. Fond\u00e9e en 1986, BC Partners a jou\u00e9 un r\u00f4le actif dans le d\u00e9veloppement du march\u00e9 de rachat europ\u00e9en pendant trois d\u00e9cennies. Aujourd\u2019hui, les cadres de BC Partners op\u00e8rent sur les march\u00e9s en tant qu\u2019\u00e9quipe int\u00e9gr\u00e9e par l\u2019entremise des bureaux de la soci\u00e9t\u00e9 en Am\u00e9rique du Nord et en Europe.<\/p>\n\n\n\n<p>Depuis sa cr\u00e9ation, BC Partners a r\u00e9alis\u00e9 105 placements en capital-investissement dans des soci\u00e9t\u00e9s d\u2019une valeur totale de 130 milliards d\u2019euros et investit actuellement son dixi\u00e8me fonds de capital-investissement. Pour de plus amples renseignements, veuillez visiter www.bcpartners.com.<\/p>\n\n\n\n<p><strong>\u00c0 propos des enseignants de l\u2019Ontario<\/strong><\/p>\n\n\n\n<p>Le R\u00e9gime de retraite des enseignantes et des enseignants de l\u2019Ontario (R\u00e9gime de retraite des enseignants et des enseignants de l\u2019Ontario) est le plus important r\u00e9gime de retraite \u00e0 profession unique au Canada, avec un actif net de 193,9 milliards de dollars au 30 juin 2018. Elle d\u00e9tient un portefeuille mondial diversifi\u00e9 d\u2019actifs, dont environ 80 % sont g\u00e9r\u00e9s \u00e0 l\u2019interne, et a gagn\u00e9 un taux de rendement annualis\u00e9 moyen de 9,9 % depuis la fondation du r\u00e9gime en 1990, jusqu\u2019au 31 d\u00e9cembre 2017. Les enseignants de l\u2019Ontario sont une organisation ind\u00e9pendante dont le si\u00e8ge social est situ\u00e9 \u00e0 Toronto. Son bureau de la r\u00e9gion Asie-Pacifique est situ\u00e9 \u00e0 Hong Kong et son bureau de la r\u00e9gion Europe, Moyen-Orient et Afrique est situ\u00e9 \u00e0 Londres. Le r\u00e9gime \u00e0 prestations d\u00e9termin\u00e9es, qui \u00e9tait enti\u00e8rement capitalis\u00e9 au 31 d\u00e9cembre 2017, investit et administre les pensions des 323 000 enseignants actifs et retrait\u00e9s de la province de l\u2019Ontario. Pour en savoir plus, visitez otpp.com et suivez-nous sur Twitter @OtppInfo.<\/p>\n\n\n\n<p><strong>\u00c0 propos de HPS Investment Partners<\/strong><\/p>\n\n\n\n<p>HPS Investment Partners (\u00ab HPS \u00bb) est une soci\u00e9t\u00e9 de placement mondiale de premier plan qui cherche \u00e0 fournir des solutions de capital cr\u00e9atives et \u00e0 g\u00e9n\u00e9rer des rendements ajust\u00e9s au risque attrayants pour nos clients. Nous g\u00e9rons diverses strat\u00e9gies dans l\u2019ensemble de la structure du capital, notamment les pr\u00eats \u00e0 effet de levier syndiqu\u00e9s et les obligations \u00e0 haut rendement, les investissements en titres de cr\u00e9ance garantis de premier rang et mezzanine n\u00e9goci\u00e9s \u00e0 titre priv\u00e9, la location sur actifs et le capital-investissement. L\u2019envergure et l\u2019ampleur de notre plateforme offrent la flexibilit\u00e9 d\u2019investir dans des entreprises de toutes tailles, par le biais de solutions standard ou personnalis\u00e9es. Nous partageons une discipline et une rigueur intellectuelles communes qui nous permettent de cr\u00e9er de la valeur pour nos clients, qui nous ont confi\u00e9 plus de 46 milliards de dollars d\u2019actifs sous gestion \u00e0 compter de septembre 2018. Pour de plus amples renseignements, veuillez visiter www.hpspartners.com.<\/p>\n\n\n\n<p><strong>\u00c0 propos des investissements du Groupe d\u2019actions<\/strong><\/p>\n\n\n\n<p>Equity Group Investments (\u00ab EGI \u00bb) est la soci\u00e9t\u00e9 d\u2019investissement priv\u00e9e fond\u00e9e par Sam Zell il y a 50 ans. Bas\u00e9e \u00e0 Chicago, EGI investit de mani\u00e8re opportuniste dans les industries et les zones g\u00e9ographiques et dans toute la structure du capital. Les investissements actuels dans le portefeuille sont dans les d\u00e9chets et l\u2019infrastructure, l\u2019\u00e9nergie, le transport et la logistique, la fabrication, les communications, les soins de sant\u00e9, l\u2019agroentreprise, l\u2019assurance et l\u2019immobilier. EGI offre un capital flexible et utilise une approche de propri\u00e9t\u00e9 engag\u00e9e pour maximiser le potentiel de ses investissements.<\/p>\n\n\n\n<p><strong>Renseignements prospectifs<\/strong><\/p>\n\n\n\n<p>Cette version peut contenir des informations prospectives, y compris, mais sans s\u2019y limiter, l\u2019acquisition propos\u00e9e de Waste Industries par GFL. Ces informations prospectives sont fond\u00e9es sur certaines hypoth\u00e8ses et analyses faites par GFL \u00e0 la lumi\u00e8re de son exp\u00e9rience et de sa perception des conditions actuelles et des d\u00e9veloppements futurs attendus, ainsi que d\u2019autres facteurs qu\u2019elle estime appropri\u00e9s dans les circonstances. Cependant, si les r\u00e9sultats, le rendement ou les r\u00e9alisations r\u00e9els seront conformes aux attentes et pr\u00e9visions de GFL est soumis aux conditions du march\u00e9 et \u00e0 un certain nombre de risques et d\u2019incertitudes connus et inconnus qui pourraient faire en sorte que les r\u00e9sultats r\u00e9els diff\u00e8rent sensiblement des attentes de GFL.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>TORONTO et RALEIGH, NC, 10 octobre 2018 \u2013 GFL Environmental Inc. (\u00ab GFL \u00bb) et Waste Industries ont annonc\u00e9 aujourd&#8217;hui qu&#8217;ils ont conclu une entente de fusion d\u00e9finitive dans le cadre d&#8217;une transaction qui \u00e9value Waste Industries \u00e0 une valeur totale d&#8217;entreprise de 2,825 milliards de dollars am\u00e9ricains (environ 3,65 milliards de dollars canadiens). La [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":10092,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[21],"tags":[126],"class_list":["post-19737","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee","tag-nouvelles-de-lentreprise"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>GFL Environmental and Waste Industries annonce une fusion - GFL Environmental Inc.<\/title>\n<meta name=\"description\" content=\"GFL Environmental Inc. (\u00ab GFL \u00bb) et Waste Industries ont annonc\u00e9 aujourd\u2019hui qu\u2019ils ont conclu une entente de fusion d\u00e9finitive.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gflenv.com\/fr\/gfl-environmental-and-waste-industries-annonce-une-fusion-creant-une-entreprise-de-services-environnementaux-de-premier-plan-en-amerique-du-nord\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"GFL Environmental and Waste Industries annonce une fusion - GFL Environmental Inc.\" \/>\n<meta property=\"og:description\" content=\"GFL Environmental Inc. (\u00ab GFL \u00bb) et Waste Industries ont annonc\u00e9 aujourd\u2019hui qu\u2019ils ont conclu une entente de fusion d\u00e9finitive.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gflenv.com\/fr\/gfl-environmental-and-waste-industries-annonce-une-fusion-creant-une-entreprise-de-services-environnementaux-de-premier-plan-en-amerique-du-nord\/\" \/>\n<meta property=\"og:site_name\" content=\"GFL Environmental Inc.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/gflenvironmental\" \/>\n<meta property=\"article:published_time\" content=\"2021-03-08T20:17:52+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2022-10-10T20:21:25+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gflenv.com\/wp-content\/uploads\/2018\/08\/GFL-Environmental-Blog.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"800\" \/>\n\t<meta property=\"og:image:height\" content=\"425\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cole Watts\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@gflenv\" \/>\n<meta name=\"twitter:site\" content=\"@gflenv\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cole Watts\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"9 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gflenv.com\\\/fr\\\/gfl-environmental-and-waste-industries-annonce-une-fusion-creant-une-entreprise-de-services-environnementaux-de-premier-plan-en-amerique-du-nord\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gflenv.com\\\/fr\\\/gfl-environmental-and-waste-industries-annonce-une-fusion-creant-une-entreprise-de-services-environnementaux-de-premier-plan-en-amerique-du-nord\\\/\"},\"author\":{\"name\":\"Cole Watts\",\"@id\":\"https:\\\/\\\/gflenv.com\\\/#\\\/schema\\\/person\\\/5b038bc1b93065bd0d8a2b66691beab1\"},\"headline\":\"GFL Environmental and Waste Industries annonce une fusion\",\"datePublished\":\"2021-03-08T20:17:52+00:00\",\"dateModified\":\"2022-10-10T20:21:25+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gflenv.com\\\/fr\\\/gfl-environmental-and-waste-industries-annonce-une-fusion-creant-une-entreprise-de-services-environnementaux-de-premier-plan-en-amerique-du-nord\\\/\"},\"wordCount\":2142,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/gflenv.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/gflenv.com\\\/fr\\\/gfl-environmental-and-waste-industries-annonce-une-fusion-creant-une-entreprise-de-services-environnementaux-de-premier-plan-en-amerique-du-nord\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gflenv.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/GFL-Environmental-Blog.jpg\",\"keywords\":[\"Nouvelles de l\u2019entreprise\"],\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"en-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/gflenv.com\\\/fr\\\/gfl-environmental-and-waste-industries-annonce-une-fusion-creant-une-entreprise-de-services-environnementaux-de-premier-plan-en-amerique-du-nord\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gflenv.com\\\/fr\\\/gfl-environmental-and-waste-industries-annonce-une-fusion-creant-une-entreprise-de-services-environnementaux-de-premier-plan-en-amerique-du-nord\\\/\",\"url\":\"https:\\\/\\\/gflenv.com\\\/fr\\\/gfl-environmental-and-waste-industries-annonce-une-fusion-creant-une-entreprise-de-services-environnementaux-de-premier-plan-en-amerique-du-nord\\\/\",\"name\":\"GFL Environmental and Waste Industries annonce une fusion - GFL Environmental Inc.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gflenv.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gflenv.com\\\/fr\\\/gfl-environmental-and-waste-industries-annonce-une-fusion-creant-une-entreprise-de-services-environnementaux-de-premier-plan-en-amerique-du-nord\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gflenv.com\\\/fr\\\/gfl-environmental-and-waste-industries-annonce-une-fusion-creant-une-entreprise-de-services-environnementaux-de-premier-plan-en-amerique-du-nord\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gflenv.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/GFL-Environmental-Blog.jpg\",\"datePublished\":\"2021-03-08T20:17:52+00:00\",\"dateModified\":\"2022-10-10T20:21:25+00:00\",\"description\":\"GFL Environmental Inc. (\u00ab GFL \u00bb) et Waste Industries ont annonc\u00e9 aujourd\u2019hui qu\u2019ils ont conclu une entente de fusion d\u00e9finitive.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gflenv.com\\\/fr\\\/gfl-environmental-and-waste-industries-annonce-une-fusion-creant-une-entreprise-de-services-environnementaux-de-premier-plan-en-amerique-du-nord\\\/#breadcrumb\"},\"inLanguage\":\"en-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gflenv.com\\\/fr\\\/gfl-environmental-and-waste-industries-annonce-une-fusion-creant-une-entreprise-de-services-environnementaux-de-premier-plan-en-amerique-du-nord\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CA\",\"@id\":\"https:\\\/\\\/gflenv.com\\\/fr\\\/gfl-environmental-and-waste-industries-annonce-une-fusion-creant-une-entreprise-de-services-environnementaux-de-premier-plan-en-amerique-du-nord\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gflenv.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/GFL-Environmental-Blog.jpg\",\"contentUrl\":\"https:\\\/\\\/gflenv.com\\\/wp-content\\\/uploads\\\/2018\\\/08\\\/GFL-Environmental-Blog.jpg\",\"width\":800,\"height\":425,\"caption\":\"GFL Environmental Blog\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gflenv.com\\\/fr\\\/gfl-environmental-and-waste-industries-annonce-une-fusion-creant-une-entreprise-de-services-environnementaux-de-premier-plan-en-amerique-du-nord\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/gflenv.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"GFL Environmental and Waste Industries annonce une fusion\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gflenv.com\\\/#website\",\"url\":\"https:\\\/\\\/gflenv.com\\\/\",\"name\":\"GFL Environmental Inc.\",\"description\":\"Waste Management &amp; Environmental Services\",\"publisher\":{\"@id\":\"https:\\\/\\\/gflenv.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gflenv.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gflenv.com\\\/#organization\",\"name\":\"GFL Environmental Inc.\",\"alternateName\":\"GFL\",\"url\":\"https:\\\/\\\/gflenv.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CA\",\"@id\":\"https:\\\/\\\/gflenv.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gflenv.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/GFL_Env_LOGO_Stacked_RGB-1.png\",\"contentUrl\":\"https:\\\/\\\/gflenv.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/GFL_Env_LOGO_Stacked_RGB-1.png\",\"width\":1569,\"height\":1627,\"caption\":\"GFL Environmental Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/gflenv.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/gflenvironmental\",\"https:\\\/\\\/x.com\\\/gflenv\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/gflenvironmental\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC4j8cdyyHcZEXgSFX-jbD5g\",\"https:\\\/\\\/www.instagram.com\\\/gflenvironmental\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gflenv.com\\\/#\\\/schema\\\/person\\\/5b038bc1b93065bd0d8a2b66691beab1\",\"name\":\"Cole Watts\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3a45da6e6e58ab41f63ddbfa8dca073fc0f7b2c5f73af711e399bc6de51bbc26?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3a45da6e6e58ab41f63ddbfa8dca073fc0f7b2c5f73af711e399bc6de51bbc26?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/3a45da6e6e58ab41f63ddbfa8dca073fc0f7b2c5f73af711e399bc6de51bbc26?s=96&d=mm&r=g\",\"caption\":\"Cole Watts\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"GFL Environmental and Waste Industries annonce une fusion - GFL Environmental Inc.","description":"GFL Environmental Inc. (\u00ab GFL \u00bb) et Waste Industries ont annonc\u00e9 aujourd\u2019hui qu\u2019ils ont conclu une entente de fusion d\u00e9finitive.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gflenv.com\/fr\/gfl-environmental-and-waste-industries-annonce-une-fusion-creant-une-entreprise-de-services-environnementaux-de-premier-plan-en-amerique-du-nord\/","og_locale":"en_US","og_type":"article","og_title":"GFL Environmental and Waste Industries annonce une fusion - GFL Environmental Inc.","og_description":"GFL Environmental Inc. (\u00ab GFL \u00bb) et Waste Industries ont annonc\u00e9 aujourd\u2019hui qu\u2019ils ont conclu une entente de fusion d\u00e9finitive.","og_url":"https:\/\/gflenv.com\/fr\/gfl-environmental-and-waste-industries-annonce-une-fusion-creant-une-entreprise-de-services-environnementaux-de-premier-plan-en-amerique-du-nord\/","og_site_name":"GFL Environmental Inc.","article_publisher":"https:\/\/www.facebook.com\/gflenvironmental","article_published_time":"2021-03-08T20:17:52+00:00","article_modified_time":"2022-10-10T20:21:25+00:00","og_image":[{"width":800,"height":425,"url":"https:\/\/gflenv.com\/wp-content\/uploads\/2018\/08\/GFL-Environmental-Blog.jpg","type":"image\/jpeg"}],"author":"Cole Watts","twitter_card":"summary_large_image","twitter_creator":"@gflenv","twitter_site":"@gflenv","twitter_misc":{"Written by":"Cole Watts","Est. reading time":"9 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gflenv.com\/fr\/gfl-environmental-and-waste-industries-annonce-une-fusion-creant-une-entreprise-de-services-environnementaux-de-premier-plan-en-amerique-du-nord\/#article","isPartOf":{"@id":"https:\/\/gflenv.com\/fr\/gfl-environmental-and-waste-industries-annonce-une-fusion-creant-une-entreprise-de-services-environnementaux-de-premier-plan-en-amerique-du-nord\/"},"author":{"name":"Cole Watts","@id":"https:\/\/gflenv.com\/#\/schema\/person\/5b038bc1b93065bd0d8a2b66691beab1"},"headline":"GFL Environmental and Waste Industries annonce une fusion","datePublished":"2021-03-08T20:17:52+00:00","dateModified":"2022-10-10T20:21:25+00:00","mainEntityOfPage":{"@id":"https:\/\/gflenv.com\/fr\/gfl-environmental-and-waste-industries-annonce-une-fusion-creant-une-entreprise-de-services-environnementaux-de-premier-plan-en-amerique-du-nord\/"},"wordCount":2142,"commentCount":0,"publisher":{"@id":"https:\/\/gflenv.com\/#organization"},"image":{"@id":"https:\/\/gflenv.com\/fr\/gfl-environmental-and-waste-industries-annonce-une-fusion-creant-une-entreprise-de-services-environnementaux-de-premier-plan-en-amerique-du-nord\/#primaryimage"},"thumbnailUrl":"https:\/\/gflenv.com\/wp-content\/uploads\/2018\/08\/GFL-Environmental-Blog.jpg","keywords":["Nouvelles de l\u2019entreprise"],"articleSection":["Non classifi\u00e9(e)"],"inLanguage":"en-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/gflenv.com\/fr\/gfl-environmental-and-waste-industries-annonce-une-fusion-creant-une-entreprise-de-services-environnementaux-de-premier-plan-en-amerique-du-nord\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/gflenv.com\/fr\/gfl-environmental-and-waste-industries-annonce-une-fusion-creant-une-entreprise-de-services-environnementaux-de-premier-plan-en-amerique-du-nord\/","url":"https:\/\/gflenv.com\/fr\/gfl-environmental-and-waste-industries-annonce-une-fusion-creant-une-entreprise-de-services-environnementaux-de-premier-plan-en-amerique-du-nord\/","name":"GFL Environmental and Waste Industries annonce une fusion - GFL Environmental Inc.","isPartOf":{"@id":"https:\/\/gflenv.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gflenv.com\/fr\/gfl-environmental-and-waste-industries-annonce-une-fusion-creant-une-entreprise-de-services-environnementaux-de-premier-plan-en-amerique-du-nord\/#primaryimage"},"image":{"@id":"https:\/\/gflenv.com\/fr\/gfl-environmental-and-waste-industries-annonce-une-fusion-creant-une-entreprise-de-services-environnementaux-de-premier-plan-en-amerique-du-nord\/#primaryimage"},"thumbnailUrl":"https:\/\/gflenv.com\/wp-content\/uploads\/2018\/08\/GFL-Environmental-Blog.jpg","datePublished":"2021-03-08T20:17:52+00:00","dateModified":"2022-10-10T20:21:25+00:00","description":"GFL Environmental Inc. (\u00ab GFL \u00bb) et Waste Industries ont annonc\u00e9 aujourd\u2019hui qu\u2019ils ont conclu une entente de fusion d\u00e9finitive.","breadcrumb":{"@id":"https:\/\/gflenv.com\/fr\/gfl-environmental-and-waste-industries-annonce-une-fusion-creant-une-entreprise-de-services-environnementaux-de-premier-plan-en-amerique-du-nord\/#breadcrumb"},"inLanguage":"en-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gflenv.com\/fr\/gfl-environmental-and-waste-industries-annonce-une-fusion-creant-une-entreprise-de-services-environnementaux-de-premier-plan-en-amerique-du-nord\/"]}]},{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/gflenv.com\/fr\/gfl-environmental-and-waste-industries-annonce-une-fusion-creant-une-entreprise-de-services-environnementaux-de-premier-plan-en-amerique-du-nord\/#primaryimage","url":"https:\/\/gflenv.com\/wp-content\/uploads\/2018\/08\/GFL-Environmental-Blog.jpg","contentUrl":"https:\/\/gflenv.com\/wp-content\/uploads\/2018\/08\/GFL-Environmental-Blog.jpg","width":800,"height":425,"caption":"GFL Environmental Blog"},{"@type":"BreadcrumbList","@id":"https:\/\/gflenv.com\/fr\/gfl-environmental-and-waste-industries-annonce-une-fusion-creant-une-entreprise-de-services-environnementaux-de-premier-plan-en-amerique-du-nord\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/gflenv.com\/"},{"@type":"ListItem","position":2,"name":"GFL Environmental and Waste Industries annonce une fusion"}]},{"@type":"WebSite","@id":"https:\/\/gflenv.com\/#website","url":"https:\/\/gflenv.com\/","name":"GFL Environmental Inc.","description":"Waste Management &amp; Environmental Services","publisher":{"@id":"https:\/\/gflenv.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gflenv.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-CA"},{"@type":"Organization","@id":"https:\/\/gflenv.com\/#organization","name":"GFL Environmental Inc.","alternateName":"GFL","url":"https:\/\/gflenv.com\/","logo":{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/gflenv.com\/#\/schema\/logo\/image\/","url":"https:\/\/gflenv.com\/wp-content\/uploads\/2025\/10\/GFL_Env_LOGO_Stacked_RGB-1.png","contentUrl":"https:\/\/gflenv.com\/wp-content\/uploads\/2025\/10\/GFL_Env_LOGO_Stacked_RGB-1.png","width":1569,"height":1627,"caption":"GFL Environmental Inc."},"image":{"@id":"https:\/\/gflenv.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/gflenvironmental","https:\/\/x.com\/gflenv","https:\/\/www.linkedin.com\/company\/gflenvironmental\/","https:\/\/www.youtube.com\/channel\/UC4j8cdyyHcZEXgSFX-jbD5g","https:\/\/www.instagram.com\/gflenvironmental"]},{"@type":"Person","@id":"https:\/\/gflenv.com\/#\/schema\/person\/5b038bc1b93065bd0d8a2b66691beab1","name":"Cole Watts","image":{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/3a45da6e6e58ab41f63ddbfa8dca073fc0f7b2c5f73af711e399bc6de51bbc26?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/3a45da6e6e58ab41f63ddbfa8dca073fc0f7b2c5f73af711e399bc6de51bbc26?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/3a45da6e6e58ab41f63ddbfa8dca073fc0f7b2c5f73af711e399bc6de51bbc26?s=96&d=mm&r=g","caption":"Cole Watts"}}]}},"_links":{"self":[{"href":"https:\/\/gflenv.com\/fr\/wp-json\/wp\/v2\/posts\/19737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gflenv.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gflenv.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gflenv.com\/fr\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"https:\/\/gflenv.com\/fr\/wp-json\/wp\/v2\/comments?post=19737"}],"version-history":[{"count":0,"href":"https:\/\/gflenv.com\/fr\/wp-json\/wp\/v2\/posts\/19737\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gflenv.com\/fr\/wp-json\/wp\/v2\/media\/10092"}],"wp:attachment":[{"href":"https:\/\/gflenv.com\/fr\/wp-json\/wp\/v2\/media?parent=19737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gflenv.com\/fr\/wp-json\/wp\/v2\/categories?post=19737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gflenv.com\/fr\/wp-json\/wp\/v2\/tags?post=19737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}