{"id":41143,"date":"2024-03-01T16:32:10","date_gmt":"2024-03-01T16:32:10","guid":{"rendered":"https:\/\/gflenv.com\/?p=41143"},"modified":"2024-03-01T16:32:12","modified_gmt":"2024-03-01T16:32:12","slug":"kristine-szpulak-une-chef-de-file-pour-les-femmes-dans-le-secteur-des-matieres-residuelles","status":"publish","type":"post","link":"https:\/\/gflenv.com\/fr\/kristine-szpulak-une-chef-de-file-pour-les-femmes-dans-le-secteur-des-matieres-residuelles\/","title":{"rendered":"Kristine Szpulak\u00a0: une chef de file pour les femmes dans le secteur des mati\u00e8res r\u00e9siduelles"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"576\" src=\"https:\/\/gflenv.com\/wp-content\/uploads\/2024\/02\/MicrosoftTeams-image-67-1024x576.jpg\" alt=\"\" class=\"wp-image-41141\" srcset=\"https:\/\/gflenv.com\/wp-content\/uploads\/2024\/02\/MicrosoftTeams-image-67-1024x576.jpg 1024w, https:\/\/gflenv.com\/wp-content\/uploads\/2024\/02\/MicrosoftTeams-image-67-300x169.jpg 300w, https:\/\/gflenv.com\/wp-content\/uploads\/2024\/02\/MicrosoftTeams-image-67-768x432.jpg 768w, https:\/\/gflenv.com\/wp-content\/uploads\/2024\/02\/MicrosoftTeams-image-67-1536x864.jpg 1536w, https:\/\/gflenv.com\/wp-content\/uploads\/2024\/02\/MicrosoftTeams-image-67-1200x675.jpg 1200w, https:\/\/gflenv.com\/wp-content\/uploads\/2024\/02\/MicrosoftTeams-image-67.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p>Au cours d\u2019une carri\u00e8re admirable de 41&nbsp;ans, Kristine&nbsp;Szpulak, directrice de la logistique chez GFL, a \u00e9t\u00e9 un mod\u00e8le pour les femmes dans le secteur des d\u00e9chets. Elle a une mine de connaissances \u00e0 partager et continue d\u2019encadrer la nouvelle g\u00e9n\u00e9ration dans ce domaine.<\/p>\n\n\n\n<p>\u00ab&nbsp;GFL est devenue un chef de file dans la promotion des femmes dans l\u2019industrie des d\u00e9chets et nous permet de prendre notre envol&nbsp;\u00bb, a d\u00e9clar\u00e9 Mme&nbsp;Szpulak.<\/p>\n\n\n\n<p>Mme Szpulak est responsable de la logistique pour l\u2019installation de traitement des d\u00e9chets liquides d\u2019Oakville, en Ontario, o\u00f9 elle dirige une \u00e9quipe de 25&nbsp;employ\u00e9s, compos\u00e9e de superviseurs, de techniciens et de conducteurs.<\/p>\n\n\n\n<p>Elle est notamment charg\u00e9e de r\u00e9server des emplois, de fournir des services aux clients du secteur p\u00e9trochimique, d\u2019affecter des \u00e9quipes, de coordonner l\u2019\u00e9quipement n\u00e9cessaire, de veiller \u00e0 ce que les employ\u00e9s soient \u00e0 jour dans leur formation et d\u2019organiser les documents essentiels. Cette liste ne fait qu\u2019effleurer le travail de Mme Szpulak.<\/p>\n\n\n\n<p>Elle s\u2019efforce de se surpasser pour tous ses clients et est fi\u00e8re d\u2019entretenir des relations \u00e0 long terme avec eux, dont beaucoup sont devenus des amis.<\/p>\n\n\n\n<p>\u00ab&nbsp;Je ne veux jamais que la r\u00e9ponse soit non; je fais tout ce que je peux pour trouver toutes les solutions possibles&nbsp;\u00bb, a d\u00e9clar\u00e9 Mme Szpulak. \u00ab&nbsp;Il y a toujours des \u00e9nigmes \u00e0 r\u00e9soudre, et c\u2019est ce que j\u2019aime dans mon travail!&nbsp;\u00bb<\/p>\n\n\n\n<p>Avant de rejoindre l\u2019industrie des d\u00e9chets, Mme Szpulak souhaitait \u00e0 l\u2019origine devenir infirmi\u00e8re. Cependant, on lui a conseill\u00e9 de changer d\u2019orientation apr\u00e8s sa premi\u00e8re ann\u00e9e d\u2019\u00e9cole d\u2019infirmi\u00e8res parce que le Canada n\u2019avait pas besoin d\u2019autant d\u2019infirmi\u00e8res \u00e0 l\u2019\u00e9poque.<\/p>\n\n\n\n<p>Craignant de ne pas avoir de travail apr\u00e8s l\u2019\u00e9cole d\u2019infirmi\u00e8res, Mme Szpulak a chang\u00e9 de voie lorsqu\u2019elle est tomb\u00e9e sur un poste d\u2019assistante dans l\u2019industrie p\u00e9trochimique.&nbsp;<\/p>\n\n\n\n<p>\u00ab&nbsp;Lorsque j\u2019ai pos\u00e9 ma candidature au poste d\u2019assistante, j\u2019ai pens\u00e9 qu\u2019il s\u2019agissait d\u2019un emploi d\u2019avenir, et je pense toujours que ce que je fais est un emploi d\u2019avenir!&nbsp;\u00bb a d\u00e9clar\u00e9 Mme Szpulak. \u00ab&nbsp;Il y aura toujours des d\u00e9chets, c\u2019est pourquoi nous avons besoin de solutions \u00e9volutives pour les g\u00e9rer.&nbsp;\u00bb<\/p>\n\n\n\n<p>Apr\u00e8s plusieurs ann\u00e9es pass\u00e9es dans des r\u00f4les de service \u00e0 la client\u00e8le, Mme Szpulak a rejoint une soci\u00e9t\u00e9 d\u2019entretien de r\u00e9servoirs, rachet\u00e9e par la suite par GFL. Au cours des 25&nbsp;derni\u00e8res ann\u00e9es, elle a principalement travaill\u00e9 dans le domaine de l\u2019exp\u00e9dition et de la logistique.<\/p>\n\n\n\n<p>Au cours de sa carri\u00e8re, Mme Szpulak a fait preuve d\u2019un grand sens de l\u2019initiative et d\u2019une grande soif d\u2019apprendre. De son exp\u00e9rience dans la vente interne au service \u00e0 la client\u00e8le et \u00e0 l\u2019exp\u00e9dition, en passant par sa promotion au poste de responsable de la logistique, elle a \u00e9t\u00e9 t\u00e9moin de nombreux changements progressifs au sein de l\u2019industrie des d\u00e9chets, y compris l\u2019augmentation du nombre de femmes parmi les employ\u00e9s.<\/p>\n\n\n\n<p>Elle accorde une grande importance au mentorat et, forte de son exp\u00e9rience, souhaite partager ses connaissances avec les autres et continuer \u00e0 promouvoir les opportunit\u00e9s pour les femmes dans les environnements de travail domin\u00e9s par les hommes.<\/p>\n\n\n\n<p>L\u2019\u00e9thique de travail de Mme Szpulak et de son \u00e9quipe parle d\u2019elle-m\u00eame, ce qui leur vaut d\u2019\u00eatre reconnues par d\u2019autres services. Elle mentionne qu\u2019ils ont aid\u00e9 une succursale voisine \u00e0 rationaliser ses syst\u00e8mes et ses op\u00e9rations.<\/p>\n\n\n\n<p>\u00ab&nbsp;J\u2019aime partager mes connaissances; ma devise est qu\u2019enseigner, c\u2019est apprendre deux fois, donc en enseignant, je me r\u00e9apprends aussi moi-m\u00eame&nbsp;\u00bb, a d\u00e9clar\u00e9 Mme&nbsp;Szpulak.<\/p>\n\n\n\n<p>En dehors du travail, Mme Szpulak aime voyager, promener son cockapoo Coco, passer du temps avec ses enfants et s\u2019immerger dans le jardin.<\/p>\n\n\n\n<p>Dans un monde o\u00f9 tout va tr\u00e8s vite, Mme Szpulak nous offre ces quelques conseils de sagesse&nbsp;: \u00ab&nbsp;N\u2019oubliez pas de marcher et non de courir, vous y&nbsp;arriverez!&nbsp;\u00bb dit-elle.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Au cours d\u2019une carri\u00e8re admirable de 41&nbsp;ans, Kristine&nbsp;Szpulak, directrice de la logistique chez GFL, a \u00e9t\u00e9 un mod\u00e8le pour les femmes dans le secteur des d\u00e9chets. Elle a une mine de connaissances \u00e0 partager et continue d\u2019encadrer la nouvelle g\u00e9n\u00e9ration dans ce domaine. \u00ab&nbsp;GFL est devenue un chef de file dans la promotion des femmes [&hellip;]<\/p>\n","protected":false},"author":7,"featured_media":19122,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[21,1],"tags":[127,124,132,123,139,120],"class_list":["post-41143","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-non-classifiee","category-uncategorized","tag-femmes-aux-dechets","tag-team-green","tag-tendance","tag-trending","tag-vert-dequipe","tag-women-in-waste"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Kristine Szpulak\u00a0: une chef de file pour les femmes dans le secteur des mati\u00e8res r\u00e9siduelles - GFL Environmental Inc.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/gflenv.com\/fr\/kristine-szpulak-une-chef-de-file-pour-les-femmes-dans-le-secteur-des-matieres-residuelles\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Kristine Szpulak : une chef de file pour les femmes dans le secteur des mati\u00e8res r\u00e9siduelles\" \/>\n<meta property=\"og:description\" content=\"Au cours d\u2019une carri\u00e8re admirable de 41&nbsp;ans, Kristine&nbsp;Szpulak, directrice de la logistique chez GFL, a \u00e9t\u00e9 un mod\u00e8le pour les femmes dans le secteur des d\u00e9chets. Elle a une mine de connaissances \u00e0 partager et continue d\u2019encadrer la nouvelle g\u00e9n\u00e9ration dans ce domaine. \u00ab&nbsp;GFL est devenue un chef de file dans la promotion des femmes [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/gflenv.com\/fr\/kristine-szpulak-une-chef-de-file-pour-les-femmes-dans-le-secteur-des-matieres-residuelles\/\" \/>\n<meta property=\"og:site_name\" content=\"GFL Environmental Inc.\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/gflenvironmental\" \/>\n<meta property=\"article:published_time\" content=\"2024-03-01T16:32:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-01T16:32:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/gflenv.com\/wp-content\/uploads\/2024\/02\/MicrosoftTeams-image-67.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"Cat Bonner\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"Kristine Szpulak : une chef de file pour les femmes dans le secteur des mati\u00e8res r\u00e9siduelles\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/gflenv.com\/wp-content\/uploads\/2024\/02\/MicrosoftTeams-image-67.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@gflenv\" \/>\n<meta name=\"twitter:site\" content=\"@gflenv\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Cat Bonner\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/gflenv.com\\\/fr\\\/kristine-szpulak-une-chef-de-file-pour-les-femmes-dans-le-secteur-des-matieres-residuelles\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gflenv.com\\\/fr\\\/kristine-szpulak-une-chef-de-file-pour-les-femmes-dans-le-secteur-des-matieres-residuelles\\\/\"},\"author\":{\"name\":\"Cat Bonner\",\"@id\":\"https:\\\/\\\/gflenv.com\\\/#\\\/schema\\\/person\\\/16a92b15d45799dffba7f6c523ccf88d\"},\"headline\":\"Kristine Szpulak\u00a0: une chef de file pour les femmes dans le secteur des mati\u00e8res r\u00e9siduelles\",\"datePublished\":\"2024-03-01T16:32:10+00:00\",\"dateModified\":\"2024-03-01T16:32:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/gflenv.com\\\/fr\\\/kristine-szpulak-une-chef-de-file-pour-les-femmes-dans-le-secteur-des-matieres-residuelles\\\/\"},\"wordCount\":745,\"commentCount\":0,\"publisher\":{\"@id\":\"https:\\\/\\\/gflenv.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/gflenv.com\\\/fr\\\/kristine-szpulak-une-chef-de-file-pour-les-femmes-dans-le-secteur-des-matieres-residuelles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gflenv.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/GFL-Environmental-Blog-v2.jpg\",\"keywords\":[\"Femmes aux d\u00e9chets\",\"TEAM GREEN\",\"TENDANCE\",\"TRENDING\",\"VERT D\u2019\u00c9QUIPE\",\"Women in Waste\"],\"articleSection\":[\"Non classifi\u00e9(e)\"],\"inLanguage\":\"en-CA\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/gflenv.com\\\/fr\\\/kristine-szpulak-une-chef-de-file-pour-les-femmes-dans-le-secteur-des-matieres-residuelles\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/gflenv.com\\\/fr\\\/kristine-szpulak-une-chef-de-file-pour-les-femmes-dans-le-secteur-des-matieres-residuelles\\\/\",\"url\":\"https:\\\/\\\/gflenv.com\\\/fr\\\/kristine-szpulak-une-chef-de-file-pour-les-femmes-dans-le-secteur-des-matieres-residuelles\\\/\",\"name\":\"Kristine Szpulak\u00a0: une chef de file pour les femmes dans le secteur des mati\u00e8res r\u00e9siduelles - GFL Environmental Inc.\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/gflenv.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/gflenv.com\\\/fr\\\/kristine-szpulak-une-chef-de-file-pour-les-femmes-dans-le-secteur-des-matieres-residuelles\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/gflenv.com\\\/fr\\\/kristine-szpulak-une-chef-de-file-pour-les-femmes-dans-le-secteur-des-matieres-residuelles\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/gflenv.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/GFL-Environmental-Blog-v2.jpg\",\"datePublished\":\"2024-03-01T16:32:10+00:00\",\"dateModified\":\"2024-03-01T16:32:12+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/gflenv.com\\\/fr\\\/kristine-szpulak-une-chef-de-file-pour-les-femmes-dans-le-secteur-des-matieres-residuelles\\\/#breadcrumb\"},\"inLanguage\":\"en-CA\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/gflenv.com\\\/fr\\\/kristine-szpulak-une-chef-de-file-pour-les-femmes-dans-le-secteur-des-matieres-residuelles\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CA\",\"@id\":\"https:\\\/\\\/gflenv.com\\\/fr\\\/kristine-szpulak-une-chef-de-file-pour-les-femmes-dans-le-secteur-des-matieres-residuelles\\\/#primaryimage\",\"url\":\"https:\\\/\\\/gflenv.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/GFL-Environmental-Blog-v2.jpg\",\"contentUrl\":\"https:\\\/\\\/gflenv.com\\\/wp-content\\\/uploads\\\/2020\\\/12\\\/GFL-Environmental-Blog-v2.jpg\",\"width\":800,\"height\":425,\"caption\":\"Outside GFL building with GFL logo on a wall and a lens flare\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/gflenv.com\\\/fr\\\/kristine-szpulak-une-chef-de-file-pour-les-femmes-dans-le-secteur-des-matieres-residuelles\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/gflenv.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Kristine Szpulak\u00a0: une chef de file pour les femmes dans le secteur des mati\u00e8res r\u00e9siduelles\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/gflenv.com\\\/#website\",\"url\":\"https:\\\/\\\/gflenv.com\\\/\",\"name\":\"GFL Environmental Inc.\",\"description\":\"Waste Management &amp; Environmental Services\",\"publisher\":{\"@id\":\"https:\\\/\\\/gflenv.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/gflenv.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-CA\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/gflenv.com\\\/#organization\",\"name\":\"GFL Environmental Inc.\",\"alternateName\":\"GFL\",\"url\":\"https:\\\/\\\/gflenv.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CA\",\"@id\":\"https:\\\/\\\/gflenv.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/gflenv.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/GFL_Env_LOGO_Stacked_RGB-1.png\",\"contentUrl\":\"https:\\\/\\\/gflenv.com\\\/wp-content\\\/uploads\\\/2025\\\/10\\\/GFL_Env_LOGO_Stacked_RGB-1.png\",\"width\":1569,\"height\":1627,\"caption\":\"GFL Environmental Inc.\"},\"image\":{\"@id\":\"https:\\\/\\\/gflenv.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/gflenvironmental\",\"https:\\\/\\\/x.com\\\/gflenv\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/gflenvironmental\\\/\",\"https:\\\/\\\/www.youtube.com\\\/channel\\\/UC4j8cdyyHcZEXgSFX-jbD5g\",\"https:\\\/\\\/www.instagram.com\\\/gflenvironmental\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/gflenv.com\\\/#\\\/schema\\\/person\\\/16a92b15d45799dffba7f6c523ccf88d\",\"name\":\"Cat Bonner\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-CA\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56e7836490cc88082e0d60c415c21ea54e5ed144b6835ce9c1476634614862a3?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56e7836490cc88082e0d60c415c21ea54e5ed144b6835ce9c1476634614862a3?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/56e7836490cc88082e0d60c415c21ea54e5ed144b6835ce9c1476634614862a3?s=96&d=mm&r=g\",\"caption\":\"Cat Bonner\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Kristine Szpulak\u00a0: une chef de file pour les femmes dans le secteur des mati\u00e8res r\u00e9siduelles - GFL Environmental Inc.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/gflenv.com\/fr\/kristine-szpulak-une-chef-de-file-pour-les-femmes-dans-le-secteur-des-matieres-residuelles\/","og_locale":"en_US","og_type":"article","og_title":"Kristine Szpulak : une chef de file pour les femmes dans le secteur des mati\u00e8res r\u00e9siduelles","og_description":"Au cours d\u2019une carri\u00e8re admirable de 41&nbsp;ans, Kristine&nbsp;Szpulak, directrice de la logistique chez GFL, a \u00e9t\u00e9 un mod\u00e8le pour les femmes dans le secteur des d\u00e9chets. Elle a une mine de connaissances \u00e0 partager et continue d\u2019encadrer la nouvelle g\u00e9n\u00e9ration dans ce domaine. \u00ab&nbsp;GFL est devenue un chef de file dans la promotion des femmes [&hellip;]","og_url":"https:\/\/gflenv.com\/fr\/kristine-szpulak-une-chef-de-file-pour-les-femmes-dans-le-secteur-des-matieres-residuelles\/","og_site_name":"GFL Environmental Inc.","article_publisher":"https:\/\/www.facebook.com\/gflenvironmental","article_published_time":"2024-03-01T16:32:10+00:00","article_modified_time":"2024-03-01T16:32:12+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/gflenv.com\/wp-content\/uploads\/2024\/02\/MicrosoftTeams-image-67.jpg","type":"image\/jpeg"}],"author":"Cat Bonner","twitter_card":"summary_large_image","twitter_title":"Kristine Szpulak : une chef de file pour les femmes dans le secteur des mati\u00e8res r\u00e9siduelles","twitter_image":"https:\/\/gflenv.com\/wp-content\/uploads\/2024\/02\/MicrosoftTeams-image-67.jpg","twitter_creator":"@gflenv","twitter_site":"@gflenv","twitter_misc":{"Written by":"Cat Bonner","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/gflenv.com\/fr\/kristine-szpulak-une-chef-de-file-pour-les-femmes-dans-le-secteur-des-matieres-residuelles\/#article","isPartOf":{"@id":"https:\/\/gflenv.com\/fr\/kristine-szpulak-une-chef-de-file-pour-les-femmes-dans-le-secteur-des-matieres-residuelles\/"},"author":{"name":"Cat Bonner","@id":"https:\/\/gflenv.com\/#\/schema\/person\/16a92b15d45799dffba7f6c523ccf88d"},"headline":"Kristine Szpulak\u00a0: une chef de file pour les femmes dans le secteur des mati\u00e8res r\u00e9siduelles","datePublished":"2024-03-01T16:32:10+00:00","dateModified":"2024-03-01T16:32:12+00:00","mainEntityOfPage":{"@id":"https:\/\/gflenv.com\/fr\/kristine-szpulak-une-chef-de-file-pour-les-femmes-dans-le-secteur-des-matieres-residuelles\/"},"wordCount":745,"commentCount":0,"publisher":{"@id":"https:\/\/gflenv.com\/#organization"},"image":{"@id":"https:\/\/gflenv.com\/fr\/kristine-szpulak-une-chef-de-file-pour-les-femmes-dans-le-secteur-des-matieres-residuelles\/#primaryimage"},"thumbnailUrl":"https:\/\/gflenv.com\/wp-content\/uploads\/2020\/12\/GFL-Environmental-Blog-v2.jpg","keywords":["Femmes aux d\u00e9chets","TEAM GREEN","TENDANCE","TRENDING","VERT D\u2019\u00c9QUIPE","Women in Waste"],"articleSection":["Non classifi\u00e9(e)"],"inLanguage":"en-CA","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/gflenv.com\/fr\/kristine-szpulak-une-chef-de-file-pour-les-femmes-dans-le-secteur-des-matieres-residuelles\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/gflenv.com\/fr\/kristine-szpulak-une-chef-de-file-pour-les-femmes-dans-le-secteur-des-matieres-residuelles\/","url":"https:\/\/gflenv.com\/fr\/kristine-szpulak-une-chef-de-file-pour-les-femmes-dans-le-secteur-des-matieres-residuelles\/","name":"Kristine Szpulak\u00a0: une chef de file pour les femmes dans le secteur des mati\u00e8res r\u00e9siduelles - GFL Environmental Inc.","isPartOf":{"@id":"https:\/\/gflenv.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/gflenv.com\/fr\/kristine-szpulak-une-chef-de-file-pour-les-femmes-dans-le-secteur-des-matieres-residuelles\/#primaryimage"},"image":{"@id":"https:\/\/gflenv.com\/fr\/kristine-szpulak-une-chef-de-file-pour-les-femmes-dans-le-secteur-des-matieres-residuelles\/#primaryimage"},"thumbnailUrl":"https:\/\/gflenv.com\/wp-content\/uploads\/2020\/12\/GFL-Environmental-Blog-v2.jpg","datePublished":"2024-03-01T16:32:10+00:00","dateModified":"2024-03-01T16:32:12+00:00","breadcrumb":{"@id":"https:\/\/gflenv.com\/fr\/kristine-szpulak-une-chef-de-file-pour-les-femmes-dans-le-secteur-des-matieres-residuelles\/#breadcrumb"},"inLanguage":"en-CA","potentialAction":[{"@type":"ReadAction","target":["https:\/\/gflenv.com\/fr\/kristine-szpulak-une-chef-de-file-pour-les-femmes-dans-le-secteur-des-matieres-residuelles\/"]}]},{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/gflenv.com\/fr\/kristine-szpulak-une-chef-de-file-pour-les-femmes-dans-le-secteur-des-matieres-residuelles\/#primaryimage","url":"https:\/\/gflenv.com\/wp-content\/uploads\/2020\/12\/GFL-Environmental-Blog-v2.jpg","contentUrl":"https:\/\/gflenv.com\/wp-content\/uploads\/2020\/12\/GFL-Environmental-Blog-v2.jpg","width":800,"height":425,"caption":"Outside GFL building with GFL logo on a wall and a lens flare"},{"@type":"BreadcrumbList","@id":"https:\/\/gflenv.com\/fr\/kristine-szpulak-une-chef-de-file-pour-les-femmes-dans-le-secteur-des-matieres-residuelles\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/gflenv.com\/"},{"@type":"ListItem","position":2,"name":"Kristine Szpulak\u00a0: une chef de file pour les femmes dans le secteur des mati\u00e8res r\u00e9siduelles"}]},{"@type":"WebSite","@id":"https:\/\/gflenv.com\/#website","url":"https:\/\/gflenv.com\/","name":"GFL Environmental Inc.","description":"Waste Management &amp; Environmental Services","publisher":{"@id":"https:\/\/gflenv.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/gflenv.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-CA"},{"@type":"Organization","@id":"https:\/\/gflenv.com\/#organization","name":"GFL Environmental Inc.","alternateName":"GFL","url":"https:\/\/gflenv.com\/","logo":{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/gflenv.com\/#\/schema\/logo\/image\/","url":"https:\/\/gflenv.com\/wp-content\/uploads\/2025\/10\/GFL_Env_LOGO_Stacked_RGB-1.png","contentUrl":"https:\/\/gflenv.com\/wp-content\/uploads\/2025\/10\/GFL_Env_LOGO_Stacked_RGB-1.png","width":1569,"height":1627,"caption":"GFL Environmental Inc."},"image":{"@id":"https:\/\/gflenv.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/gflenvironmental","https:\/\/x.com\/gflenv","https:\/\/www.linkedin.com\/company\/gflenvironmental\/","https:\/\/www.youtube.com\/channel\/UC4j8cdyyHcZEXgSFX-jbD5g","https:\/\/www.instagram.com\/gflenvironmental"]},{"@type":"Person","@id":"https:\/\/gflenv.com\/#\/schema\/person\/16a92b15d45799dffba7f6c523ccf88d","name":"Cat Bonner","image":{"@type":"ImageObject","inLanguage":"en-CA","@id":"https:\/\/secure.gravatar.com\/avatar\/56e7836490cc88082e0d60c415c21ea54e5ed144b6835ce9c1476634614862a3?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/56e7836490cc88082e0d60c415c21ea54e5ed144b6835ce9c1476634614862a3?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/56e7836490cc88082e0d60c415c21ea54e5ed144b6835ce9c1476634614862a3?s=96&d=mm&r=g","caption":"Cat Bonner"}}]}},"_links":{"self":[{"href":"https:\/\/gflenv.com\/fr\/wp-json\/wp\/v2\/posts\/41143","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/gflenv.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/gflenv.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/gflenv.com\/fr\/wp-json\/wp\/v2\/users\/7"}],"replies":[{"embeddable":true,"href":"https:\/\/gflenv.com\/fr\/wp-json\/wp\/v2\/comments?post=41143"}],"version-history":[{"count":0,"href":"https:\/\/gflenv.com\/fr\/wp-json\/wp\/v2\/posts\/41143\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/gflenv.com\/fr\/wp-json\/wp\/v2\/media\/19122"}],"wp:attachment":[{"href":"https:\/\/gflenv.com\/fr\/wp-json\/wp\/v2\/media?parent=41143"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/gflenv.com\/fr\/wp-json\/wp\/v2\/categories?post=41143"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/gflenv.com\/fr\/wp-json\/wp\/v2\/tags?post=41143"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}